{"id":387,"date":"2025-01-24T05:58:01","date_gmt":"2025-01-24T05:58:01","guid":{"rendered":"https:\/\/pdedoncker.be\/?page_id=387"},"modified":"2025-12-06T05:35:22","modified_gmt":"2025-12-06T04:35:22","slug":"correction-du-menton","status":"publish","type":"page","link":"https:\/\/pdedoncker.be\/fr\/behandelingen\/kincorrectie\/","title":{"rendered":"Correction du menton"},"content":{"rendered":"<h4><\/h4>\t\t\t\t\t\n\t<nav aria-label=\"chapelure\"><p><a href=\"https:\/\/pdedoncker.be\/fr\/\">Accueil<\/a> \/ <a href=\"https:\/\/pdedoncker.be\/fr\/traitements\/\">Traitements<\/a> \/ Kincorrectie<\/p><\/nav>\n\t\t\t\t<a href=\"https:\/\/g.page\/r\/CZbKKXUNDXtNEAE\/review\"  target=\"_blank\" rel=\"noopener\"  itemprop=\"url\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/pdedoncker.be\/wp-content\/uploads\/2025\/12\/google-emblem-patrick.svg\" alt=\"google-emblem-patrick\" itemprop=\"image\" height=\"56\" width=\"450\" title=\"google-emblem-patrick\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t<\/a>\n<h2>\n\t\t\tTraitement\t<\/h2>\n\t<p>Le menton et le nez d\u00e9terminent en grande partie le profil d'un visage. Lorsque le double menton et le cou se confondent presque, une proth\u00e8se de menton peut consid\u00e9rablement embellir la vue de c\u00f4t\u00e9. Le menton gagne en projection et la m\u00e2choire est mieux d\u00e9finie. Une correction du menton permet d'ajuster \u00e0 la fois la taille et la forme du menton.<\/p>\n<p>Ce traitement est parfois associ\u00e9 \u00e0 une liposculpture du cou afin de d\u00e9limiter clairement l'angle entre le cou et le double menton.<\/p>\n<p>Chaque correction du menton est adapt\u00e9e aux souhaits individuels du patient. Le chirurgien plasticien veille \u00e0 ce que la correction soit en harmonie avec le corps et le visage.<\/p>\n<h2>\n\t\t\tLa technologie\t<\/h2>\n\t<p>\u00c0 l'aide d'une photo en gros plan, le chirurgien plasticien discute de ce qui est possible et s'enquiert de vos souhaits. La correction du menton se fait g\u00e9n\u00e9ralement par l'insertion d'un implant par la bouche. Une autre option pour corriger le menton est l'injection de votre propre tissu adipeux, ou lipofilling.<\/p>\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/pdedoncker.be\/wp-content\/uploads\/2025\/01\/kincorrectie-foto.jpg\" alt=\"photo de correction du menton\" itemprop=\"image\" height=\"528\" width=\"788\" title=\"photo de correction du menton\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t<a href=\"\/fr\/liste-de-prix\/\" target=\"_self\">\n\t\t\t\t\t\t\tVoir les tarifs\n\t\t\t\t\t<\/a>\n\t\t\t<a href=\"\/fr\/contact\/\" target=\"_self\">\n\t\t\t\t\t\t\tPrendre contact\n\t\t\t\t\t<\/a>\n\t\t\tavant et apr\u00e8s\n\t\t\t\t\t\t<h4>Voir les r\u00e9sultats avant et apr\u00e8s ce traitement<\/h4>\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/pdedoncker.be\/wp-content\/uploads\/2025\/02\/83794.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/pdedoncker.be\/wp-content\/uploads\/2025\/02\/83792.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/pdedoncker.be\/wp-content\/uploads\/2025\/02\/135916.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/pdedoncker.be\/wp-content\/uploads\/2025\/02\/135913.jpg\" alt=\"\"\/>\n\t\t\t<a href=\"\/fr\/contact\/\" target=\"_self\">\n\t\t\t\t\t\t\tContactez nous\n\t\t\t\t\t<\/a>\n\t\t\t\t<a href=\"https:\/\/realplasticsurgeon.eu\/search\/doctor\/ZGV4\" target=\"_blank\" rel=\"noopener\" itemprop=\"url\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/pdedoncker.be\/wp-content\/uploads\/2025\/12\/certifcation-rps-whitebg.png\" alt=\"certification-rps-whitebg\" itemprop=\"image\" height=\"219\" width=\"141\" title=\"certification-rps-whitebg\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t<\/a>\n            <img decoding=\"async\" src=\"https:\/\/pdedoncker.be\/wp-content\/uploads\/2025\/01\/maki_doctor.svg\" alt=\"Ic\u00f4ne du client satisfait\"\/>\n            Dr Patrick Dedoncker<br \/>Erkend plastisch chirurg\n\t\t\tProfessionele zorg door een erkend specialist\n\t\t\t\t\t\t<h2>Pourquoi choisir Dr. Patrick Dedoncker ?<\/h2>\t\t\t\t\t\n\t<ul>\n\t\t\t<li>\n\t\t\t\t<b>Certifi\u00e9<\/b> et <b>enregistr\u00e9<\/b> au minist\u00e8re belge de la sant\u00e9\n\t\t\t<\/li>\n\t\t\t<li>\n\t\t\t\tMembre de la<b> Soci\u00e9t\u00e9 royale belge de chirurgie plastique (RBSPS)<\/b>\n\t\t\t<\/li>\n\t\t\t<li>\n\t\t\t\t<b>Une solide r\u00e9putation<\/b> en chirurgie mammaire, faciale et corporelle\n\t\t\t<\/li>\n\t\t\t<li>\n\t\t\t\tInterventions uniquement en <b>environnements hospitaliers agr\u00e9\u00e9s <\/b>avec un soutien m\u00e9dical complet\n\t\t\t<\/li>\n\t\t\t<li>\n\t\t\t\tCollaboration multidisciplinaire en milieu hospitalier pour <b>une s\u00e9curit\u00e9 optimale pour les patients<\/b>\n\t\t\t<\/li>\n\t\t\t<li>\n\t\t\t\tSeulement <b>les techniques chirurgicales modernes<\/b> conform\u00e9ment \u00e0 la norme internationale\n\t\t\t<\/li>\n\t\t<\/ul>\n<h2>\n\t\t\tInformations importantes\t<\/h2>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pdedoncker.be\/wp-content\/uploads\/2025\/01\/voorzorgen.svg\" alt=\"pr\u00e9cautions\" width=\"61\" height=\"61\" \/>\n\t\t\t\t\t\t<h4>Pr\u00e9cautions<\/h4>\t\t\t\t\t\n\t\t\t<p>Al onze ingrepen worden in de meest veilige omstandigheden uitgevoerd door de plastisch chirurg, die wordt bijgestaan door een professioneel team.Hoewel een kincorrectie meestal onder lokale verdoving gebeurt, wordt u tijdens de ingreep toch continu gemonitord (automatische, herhaaldelijke bloeddrukmetingen, constante zuurstofsaturatie metingen, electrocardiogram). E\u00e9n of twee gediplomeerde verpleegkundigen maken deel uit van het team. Alleen deze werkwijze garandeert de hoogst mogelijke veiligheid voor u als pati\u00ebnt.De plaatselijke verdoving zorgt niet alleen voor een ingreep zonder pijn, maar ook voor minimaal bloedverlies en blauwe plekkenWanneer u bloedverdunnende medicijnen gebruikt, gelieve dit vooraf mee te delen aan uw plastisch chirurg (bv. acetylsalicylzuur, aspirine, asaflow, cardioaspirine, dipiridamole, plavix, sintrom, marevan e.a.).Na uw ingreep krijgt u het persoonlijk mobiel GSM-nummer van uw plastisch chirurg zodat u zich veilig voelt.<\/p>\t\t\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pdedoncker.be\/wp-content\/uploads\/2025\/01\/verdoving.svg\" alt=\"anesth\u00e9sie\" width=\"61\" height=\"61\" \/>\n\t\t\t\t\t\t<h4>Anesth\u00e9sie<\/h4>\t\t\t\t\t\n\t\t\t<p>En g\u00e9n\u00e9ral, une anesth\u00e9sie locale suffit. Un s\u00e9datif de courte dur\u00e9e est administr\u00e9 aux patients nerveux. Cette anesth\u00e9sie peut se d\u00e9cliner en plusieurs degr\u00e9s, jusqu'\u00e0 l'anesth\u00e9sie de sommeil.<\/p>\t\t\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pdedoncker.be\/wp-content\/uploads\/2025\/01\/herstel.svg\" alt=\"r\u00e9cup\u00e9ration\" width=\"61\" height=\"61\" \/>\n\t\t\t\t\t\t<h4>R\u00e9cup\u00e9ration<\/h4>\t\t\t\t\t\n\t\t\t<p>Apr\u00e8s l'intervention, votre menton peut \u00eatre l\u00e9g\u00e8rement gonfl\u00e9 et bleu. Cette g\u00eane dispara\u00eet au bout de quelques jours. Vous ne ressentirez que peu ou pas de douleur apr\u00e8s la plastie du menton.<br \/><br \/>L'intervention se faisant par la bouche, il n'est pas n\u00e9cessaire de porter un pansement. Vous pouvez donc reprendre vos activit\u00e9s imm\u00e9diatement.<br \/><br \/>Pour votre confort, nous vous recommandons de ne pas manger pendant les premiers jours suivant l'intervention. Nous recommandons \u00e9galement une d\u00e9sinfection r\u00e9guli\u00e8re de la bouche avec un bain de bouche \u00e0 l'isob\u00e9tadine pendant la premi\u00e8re semaine suivant l'intervention.<\/p>\t\t\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pdedoncker.be\/wp-content\/uploads\/2025\/01\/risicos.svg\" alt=\"risques\" width=\"61\" height=\"61\" \/>\n\t\t\t\t\t\t<h4>Risques \u00e9ventuels<\/h4>\t\t\t\t\t\n\t\t\t<p>Wanneer u gezond bent, zijn er nauwelijks risico&#8217;s verbonden aan deze ingreep. Door de combinatie van antibiotica tijdens de ingreep en ontsmettende mondspoelingen met isobetadine, treedt infectie zelden op.<br \/><br \/>Votre chirurgien plasticien veille \u00e0 ce que votre nouveau profil soit en parfaite harmonie avec le reste de votre visage.<\/p>\t\t\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pdedoncker.be\/wp-content\/uploads\/2025\/01\/litteken.svg\" alt=\"cicatrice\" width=\"61\" height=\"61\" \/>\n\t\t\t\t\t\t<h4>Cicatrice<\/h4>\t\t\t\t\t\n\t\t\t<p>Il n'y a pas de cicatrice car l'implant est ins\u00e9r\u00e9 par la bouche. Les sutures internes se dissolvent spontan\u00e9ment.<\/p>\t\t\n\t\t\tCe que disent nos patients satisfaits\n\t\t\t\t\t\t<h4>Nos patients satisfaits nous font part de leur exp\u00e9rience.<\/h4>\t\t\t\t\t\n\t\t\t<p>Lisez leurs t\u00e9moignages et d\u00e9couvrez comment notre approche personnalis\u00e9e de la chirurgie plastique les a aid\u00e9s \u00e0 renforcer leur confiance en eux, \u00e0 atteindre leurs objectifs et \u00e0 se sentir mieux dans leur peau. Votre histoire pourrait \u00eatre la prochaine !<\/p>\t\t\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/pdedoncker.be\/wp-content\/uploads\/2025\/01\/reviews-blok-img.jpg\" alt=\"critiques-block-img\" itemprop=\"image\" height=\"419\" width=\"735\" title=\"critiques-block-img\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t<!-- Slides wrapper -->\n\t\t\t\t\t\t<cite>\n\t\t\t\t\t\t\tricia matha-amana\n\t<i>\u2605<\/i><i>\u2605<\/i><i>\u2605<\/i><i>\u2605<\/i><i>\u2605<\/i>\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/cite>\n\t\t\t\t\t\t\t<p>Le Dr Patrick Dedoncker est l'un des meilleurs Dr. C'est un docteur qui a du c\u0153ur quand vous parlez \u00e0 cet homme la premi\u00e8re chose que vous remarquez c'est qu'avec lui ce n'est pas une question d'argent mais de s\u00e9curit\u00e9 pour le patient. Je me suis sentie en s\u00e9curit\u00e9 avec lui le jour de l'op\u00e9ration. Le 26 novembre 2024, j'ai \u00e9t\u00e9 op\u00e9r\u00e9e par le Dr Patrick Dedoncker. Cela fait maintenant un mois exactement que j'ai \u00e9t\u00e9 op\u00e9r\u00e9e par le Dr Patrick Dedoncker. Je suis tr\u00e8s satisfaite de ma poitrine gr\u00e2ce \u00e0 l'op\u00e9ration, je me sens belle et heureuse.<\/p>\t\t\t\t\t\t\n\t\t\t\t\t\t<cite>\n\t\t\t\t\t\t\tmorgane van den eynden\n\t<i>\u2605<\/i><i>\u2605<\/i><i>\u2605<\/i><i>\u2605<\/i><i>\u2605<\/i>\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/cite>\n\t\t\t\t\t\t\t<p>Si vous \u00eates \u00e0 la recherche d'un chirurgien plasticien fiable et professionnel, vous \u00eates au bon endroit. Il vous met \u00e0 l'aise et tr\u00e8s \u00e0 l'aise ! Il vous \u00e9coute tr\u00e8s bien en tant que patient. Si quelque chose n'allait pas, vous pouviez le joindre tr\u00e8s rapidement et efficacement ! Absolument recommand\u00e9, merci beaucoup pour les soins fantastiques et le r\u00e9sultat extr\u00eamement beau !<\/p>\t\t\t\t\t\t\n\t\t\t\t\t\t<cite>\n\t\t\t\t\t\t\t Valery Perez Rodriguez\n\t<i>\u2605<\/i><i>\u2605<\/i><i>\u2605<\/i><i>\u2605<\/i><i>\u2605<\/i>\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/cite>\n\t\t\t\t\t\t\t<p>Chirurgien tr\u00e8s s\u00e9rieux et honn\u00eate. J'ai \u00e9t\u00e9 op\u00e9r\u00e9e des seins par le Dr Dedoncker et je suis tr\u00e8s satisfaite du r\u00e9sultat naturel. Le docteur a pris le temps de v\u00e9rifier le type d'implant et la taille qui conviendrait le mieux \u00e0 ma silhouette.Contrairement \u00e0 ce que dit l'un des avis, il y a bien un suivi post-op\u00e9ratoire avec une visite de contr\u00f4le pour v\u00e9rifier la cicatrisation et\/ou retirer les points de suture si n\u00e9cessaire. Je recommande !<\/p>\t\t\t\t\t\t\n\t\t\t\t\t\t<cite>\n\t\t\t\t\t\t\tsigrid bosmans\n\t<i>\u2605<\/i><i>\u2605<\/i><i>\u2605<\/i><i>\u2605<\/i><i>\u2605<\/i>\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/cite>\n\t\t\t\t\t\t\t<p>Tr\u00e8s satisfaite du Docteur Dedoncker ! J'ai subi une op\u00e9ration des paupi\u00e8res il y a quelques ann\u00e9es et j'en suis toujours tr\u00e8s satisfaite ! Il y a un mois, il m'a fait une liposuccion et cela avance \u00e9galement dans la bonne direction. Le docteur a pris son temps et m'a donn\u00e9 suffisamment d'informations. Ce qui est tr\u00e8s rassurant, c'est qu'il donne son num\u00e9ro de portable en cas de questions\/avis et ainsi de suite. Exp\u00e9rience tr\u00e8s positive.<\/p>\t\t\t\t\t\t\n\t\t\t\t\t\t<cite>\n\t\t\t\t\t\t\tV\u00e9ronique Baeten\n\t<i>\u2605<\/i><i>\u2605<\/i><i>\u2605<\/i><i>\u2605<\/i><i>\u2605<\/i>\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/cite>\n\t\t\t\t\t\t\t<p>Pour moi, le Docteur Dedoncker est un chirurgien tr\u00e8s comp\u00e9tent et direct. J'ai d\u00e9j\u00e0 fait appel \u00e0 lui deux fois et je suis extr\u00eamement satisfaite du r\u00e9sultat, de son approche et de sa flexibilit\u00e9. Ce qui me g\u00eanait dans le pass\u00e9, il l'a r\u00e9solu \u00e0 merveille... Merci beaucoup !<\/p>\t\t\t\t\t\t\n\t\t\t\t\t\t<cite>\n\t\t\t\t\t\t\tMaria Rahman\n\t<i>\u2605<\/i><i>\u2605<\/i><i>\u2605<\/i><i>\u2605<\/i><i>\u2605<\/i>\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/cite>\n\t\t\t\t\t\t\t<p>Meilleure exp\u00e9rience. Je suis all\u00e9e pour une augmentation mammaire, une correction de l'ar\u00e9ole et un lifting. Parfaitement r\u00e9alis\u00e9. Toujours disponible, bonne consultation, m\u00eame le week-end. Le r\u00e9sultat est excellent et je peux toujours le joindre pour toute r\u00e9clamation. Je ferai certainement d'autres op\u00e9rations ici. L'hygi\u00e8ne \u00e9tait \u00e9galement excellente. Les soins postop\u00e9ratoires \u00e9taient \u00e9galement bien organis\u00e9s. Hautement recommand\u00e9.\u00a0<\/p>\t\t\t\t\t\t\n\t\t\t\t\t\t<cite>\n\t\t\t\t\t\t\tMonique Lissens\n\t<i>\u2605<\/i><i>\u2605<\/i><i>\u2605<\/i><i>\u2605<\/i><i>\u2605<\/i>\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/cite>\n\t\t\t\t\t\t\t<p>Le 5 novembre 2024, j'ai contact\u00e9 le Dr Dedoncker pour un probl\u00e8me de rides du visage. Il a examin\u00e9 avec moi ce qu'il fallait faire. Il m'a propos\u00e9 de corriger \u00e9galement mes paupi\u00e8res. J'ai suivi son conseil. Il m'a donc fait un mini lift et une plastie v\u00e9sicale. Nous sommes 3 mois plus tard. Je suis ravie du r\u00e9sultat. C'est exactement ce que je voulais : des traits du visage qui restent naturels et une nette am\u00e9lioration du regard ! Merci docteur. Je vous recommande \u00e0 tous ceux qui me demandent o\u00f9 je suis all\u00e9e pour obtenir un si bon r\u00e9sultat.<\/p>\t\t\t\t\t\t\n\t\t\t\t<!-- Pagination, if required -->\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/pdedoncker.be\/wp-content\/uploads\/2025\/01\/consult-verloop-img.jpg\" alt=\"consultation-course-img\" itemprop=\"image\" height=\"584\" width=\"878\" title=\"consultation-course-img\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\tVotre chemin vers l'assurance\n\t\t\t\t\t\t<h4>Comment se d\u00e9roule un rendez-vous dans notre clinique<\/h4>\t\t\t\t\t\n\t\t\t<p>Dans notre clinique, nous adoptons une approche personnelle et experte pour renforcer votre confiance en vous et obtenir les meilleurs r\u00e9sultats.<\/p>\t\t\n    <img decoding=\"async\" src=\"https:\/\/pdedoncker.be\/wp-content\/uploads\/2025\/01\/miniprofielfoto.png\" alt=\"Dr. Patrick Dedoncker\"\/>\n      <h1>Dr. Patrick Dedoncker<\/h1>\n      <p>Chirurgien plasticien certifi\u00e9<\/p>\n\t\t\t01. \n\t\t\t\t\t\t<h4>Prendre rendez-vous<\/h4>\t\t\t\t\t\n\t\t\t<p>Il vous suffit de prendre rendez-vous en ligne ou par t\u00e9l\u00e9phone. Choisissez l'heure qui vous convient et faites-nous part \u00e0 l'avance de vos souhaits ou questions sp\u00e9cifiques.<\/p>\t\t\n\t\t\t02. \n\t\t\t\t\t\t<h4>Consultation<\/h4>\t\t\t\t\t\n\t\t\t<p>Lors de la consultation, le Dr Patrick Dedoncker discute de vos souhaits et de vos attentes. Nous proc\u00e9dons \u00e0 une analyse compl\u00e8te afin d'\u00e9tablir un plan de traitement personnalis\u00e9.<\/p>\t\t\n\t\t\t03. \n\t\t\t\t\t\t<h4>Apprendre \u00e0 conna\u00eetre<\/h4>\t\t\t\t\t\n\t\t\t<p>Rencontrez notre chirurgien plasticien certifi\u00e9, qui examinera votre plan de traitement en d\u00e9tail avec vous. Ensemble, nous d\u00e9terminerons la meilleure approche pour obtenir le r\u00e9sultat souhait\u00e9.<\/p>\t\t\n\t\t\t04. \n\t\t\t\t\t\t<h4>Traitement et soins<\/h4>\t\t\t\t\t\n\t\t\t<p>Faites l'exp\u00e9rience de soins et de conseils professionnels, adapt\u00e9s \u00e0 vos besoins. Nous veillons \u00e0 ce que vous vous sentiez \u00e0 l'aise et bien soutenu pendant et apr\u00e8s le traitement.<\/p>\t\t\n\t\t\t<a href=\"\/fr\/rendez-vous-en-ligne\/\" target=\"_self\">\n\t\t\t\t\t\t\tPrendre un rendez-vous en ligne\n\t\t\t\t\t<\/a>\n\t\t\t<a href=\"\/fr\/contact\/\" target=\"_self\">\n\t\t\t\t\t\t\tContactez nous\n\t\t\t\t\t<\/a>\n<h2>\n\t\t\tContactez nous\t<\/h2>\n\t<p>Vous avez des questions ou souhaitez prendre rendez-vous ? Remplissez le formulaire de contact et nous vous contacterons dans les 24 heures pour vous aider davantage !<\/p>\n\t\t\t\t\t\t<h4>Se sentir plus confiant que jamais !<\/h4>\t\t\t\t\t\n\t\t\t<p>Pr\u00eat \u00e0 franchir le pas vers une plus grande confiance en soi ? Prenez d\u00e8s \u00e0 pr\u00e9sent rendez-vous avec nous pour une op\u00e9ration de chirurgie plastique et b\u00e9n\u00e9ficiez de soins personnalis\u00e9s adapt\u00e9s \u00e0 vos besoins.<\/p>","protected":false},"excerpt":{"rendered":"<p>Home \/ Behandelingen \/ Kincorrectie De behandeling De kin en de neus bepalen in belangrijke mate het profiel van een gezicht. Wanneer de onderkin en de hals bijna in elkaar overlopen, kan een kinprothese het zijaanzicht aanzienlijk verfraaien. De kin krijgt meer projectie en de kaaklijn is meer afgelijnd. Bij een kincorrectie kan zowel de&hellip;<\/p>","protected":false},"author":1,"featured_media":0,"parent":155,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-387","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/pdedoncker.be\/fr\/wp-json\/wp\/v2\/pages\/387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pdedoncker.be\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pdedoncker.be\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pdedoncker.be\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pdedoncker.be\/fr\/wp-json\/wp\/v2\/comments?post=387"}],"version-history":[{"count":11,"href":"https:\/\/pdedoncker.be\/fr\/wp-json\/wp\/v2\/pages\/387\/revisions"}],"predecessor-version":[{"id":1587,"href":"https:\/\/pdedoncker.be\/fr\/wp-json\/wp\/v2\/pages\/387\/revisions\/1587"}],"up":[{"embeddable":true,"href":"https:\/\/pdedoncker.be\/fr\/wp-json\/wp\/v2\/pages\/155"}],"wp:attachment":[{"href":"https:\/\/pdedoncker.be\/fr\/wp-json\/wp\/v2\/media?parent=387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}